{"id":49642,"date":"2024-08-09T10:34:04","date_gmt":"2024-08-09T14:34:04","guid":{"rendered":"https:\/\/martinluther.ca\/?p=49642"},"modified":"2024-10-14T20:33:12","modified_gmt":"2024-10-15T00:33:12","slug":"downtown-toronto-mit-dem-bus-am-sonntag-17-november-2024-fur-deutschsprachige-senioren","status":"publish","type":"post","link":"https:\/\/martinluther.ca\/de\/2024\/08\/downtown-toronto-mit-dem-bus-am-sonntag-17-november-2024-fur-deutschsprachige-senioren\/","title":{"rendered":"Stadttour durch das Herzen Torontos \u2014im Luxusbus\u2014 am 17. 11. 2024 f\u00fcr deutschsprachigen Senioren"},"content":{"rendered":"<p class=\"p1\">UPDATE 6. Oktober 2024: Aufgrund mangelnder Anmeldungen abgesagt. Verschoben auf Fr\u00fchjahr 2025.<\/p>\n<p class=\"p1\"><strong>Orginalbeitrag 0. August 2024:<\/strong> Egal ob Sie neu in Toronto sind, oder seit der COVID-Lockdownzeit (oder noch l\u00e4nger) nicht mehr in der Innenstadt waren, k\u00f6nnen Sie nun die Stadt im Komfort eines luxuri\u00f6sen, klimatisierten Reisebusses (mit 56 Sitzen) neu entdecken!<\/p>\n<p class=\"p1\">Sie erleben eine abwechselungsreiche Sightseeing-Tour durch die gr\u00f6\u00dfte Metropole Kanadas mit einem erfahrenen deutschsprachigen Reiseleiter und einem Profi-Busfahrer, die uns gekonnt durch das gesch\u00e4ftige Treiben und den \u00fcberw\u00e4ltigenden Verkehr f\u00fchren.<\/p>\n<p class=\"p1\">Die gesamte Tour wird in deutscher Sprache durchgef\u00fchrt und richtet sich in erster Linie an deutschsprachige Senioren (und ihre Begleiter\/Betreuer) im Gro\u00dfraum Toronto (GTA), da sie durch einen Zuschuss des einzigen deutschsprachigen Seniorenwohnheims in Toronto, das <strong>Moll-Berczy-Haus<\/strong>\u00a0mitfinanziert wird.<\/p>\n<p class=\"p4\"><b>Wir treffen uns um 8.30 Uhr in der Martin-Luther-Kirche (2379 Lake Shore Blvd West) in Etobicoke und sind voraussichtlich gegen 15.00 Uhr wieder zur\u00fcck.<\/b><\/p>\n<p class=\"p4\"><b>Kosten: $35 \/Person <\/b><span class=\"s1\"><b>*<\/b><\/span><\/p>\n<p class=\"p4\"><b>Voranmeldung: bis 6. Oktober 2024 (desutsches Erntedank-Sonntag) (per E-Mail) <a href=\"mailto:office@martinluther.ca\"><span class=\"s3\">office@martinluther.ca<\/span><\/a>\u00a0 (per Tel.): 416-251-8293. <\/b>Um fest zu reservieren, \u00fcberweisen Sie bitte den Eigenkostenanteil von $35 &#8211;am besten&#8211; per INTERAC E-Transfer oder PAYPAL an: <a href=\"mailto:treasurer@martinluther.ca\" target=\"_blank\" rel=\"noopener\"><strong>treasurer@martinluther.ca<\/strong><\/a>. Bitte f\u00fcgen Sie unbedingt<strong> eine Notiz<\/strong> mit der Anzahl der Personen, den Namen jeder Person und den Kontaktdaten mit Ihrer Telefonnummer und\/oder E-Mail-Adresse bei.<\/p>\n<p>Teilnehmer sollten eigene Lunchpakete und etwas Bargeld (als Trinkgeld f\u00fcr den <strong>Coach Canada<\/strong> Busfahrer) mitbringen.<\/p>\n<p class=\"p4\"><b>Fahrtroute:<\/b>\u00a0(u.a.) altes und neues Rathaus, Eaton Centre, Yonge Street, Parlamentsgeb\u00e4ude, Campus der Universit\u00e4t-Toronto, Royal Ontario Museum, <i>Church of the Redeemer,<\/i> Yorkville, Bay Street, \u00f6stlich vorbei am Moll Berczy Park, dem <i>B\u00fcgeleisen Geb\u00e4ude <\/i>(Flat Iron Bldg.) und dem St. Lorenz Markt sowie dem <i>Brennerei-Viertel<\/i> (Distillery District).<\/p>\n<p class=\"p4\">Ferner wird an Harbourfront, Queen\u2019s Quay, dem ber\u00fchmten CN Tower, dem riesigen Rogers Centre Stadium (fr\u00fcher SkyDome), dem Mode- und Textilviertel bzw. Chinatown vorbei gefahren.<\/p>\n<p class=\"p4\"><b>Bitte helfen Sie mit <i>\u201cdie Werbetrommel zu r\u00fchren\u201d.<\/i><\/b><span class=\"s4\">\u00a0S<\/span>agen Sie es weiter im Kreise Ihrer deutschsprachigen Freunde und Bekannten in Ganz-GTA \u2014egal ob sie zu anderen Gemeinden geh\u00f6ren (z.B. St. George&#8217;s Lutheran Church, First Evangelical Lutheran Church, Glebe Road United Church, St Patrick&#8217;s Catholic Church); oder zu den deutschsprachigen Schulen (German International School Toronto, Deutsche Sprachschulen Metro Toronto), diverse Kreisen o. Klubs (z. B. Hansa Haus); oder den Konsulaten der <b>D-A-CH<\/b> L\u00e4nder (ein Apronym f\u00fcr Deutschland, \u00d6sterreich und die Schweiz), etc.<\/p>\n<p><span class=\"s1\">* <\/span><span class=\"s2\">Anmerkung: <\/span>Die eigentlichen Kosten (pro Person) betragen ca. $67.<span class=\"Apple-converted-space\">\u00a0\u00a0<\/span>Der Zuschuss des Moll-Berczy-Haus f\u00fcr deutschsprachige Senioren (im Gro\u00dfraum Toronto) erm\u00f6glicht den erm\u00e4\u00dfigten Preis!<\/p>\n<p class=\"p4\">Hinweis\/Haftungsausschluss: Aufgrund von Stra\u00dfenbauarbeiten und damit verbundenen Verkehrsstaus k\u00f6nnen geringf\u00fcgige \u00c4nderungen der Fahrroute bzw. Anlaufstellen erforderlich werden.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-49749\" src=\"https:\/\/martinluther.ca\/wp-content\/uploads\/2024\/08\/2024-11-17-Toronto-Bus-Tour-in-German-for-Seniors-Sq-image-ad.jpg\" alt=\"\" width=\"1080\" height=\"1080\" srcset=\"https:\/\/martinluther.ca\/wp-content\/uploads\/2024\/08\/2024-11-17-Toronto-Bus-Tour-in-German-for-Seniors-Sq-image-ad.jpg 1080w, https:\/\/martinluther.ca\/wp-content\/uploads\/2024\/08\/2024-11-17-Toronto-Bus-Tour-in-German-for-Seniors-Sq-image-ad-300x300.jpg 300w, https:\/\/martinluther.ca\/wp-content\/uploads\/2024\/08\/2024-11-17-Toronto-Bus-Tour-in-German-for-Seniors-Sq-image-ad-1024x1024.jpg 1024w, https:\/\/martinluther.ca\/wp-content\/uploads\/2024\/08\/2024-11-17-Toronto-Bus-Tour-in-German-for-Seniors-Sq-image-ad-150x150.jpg 150w, https:\/\/martinluther.ca\/wp-content\/uploads\/2024\/08\/2024-11-17-Toronto-Bus-Tour-in-German-for-Seniors-Sq-image-ad-768x768.jpg 768w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-49612\" src=\"https:\/\/martinluther.ca\/wp-content\/uploads\/2024\/08\/2024-11-17-Coach-Canada-bus-for-Downtown-Toronto-tour.jpg\" alt=\"\" width=\"1700\" height=\"2200\" srcset=\"https:\/\/martinluther.ca\/wp-content\/uploads\/2024\/08\/2024-11-17-Coach-Canada-bus-for-Downtown-Toronto-tour.jpg 1700w, https:\/\/martinluther.ca\/wp-content\/uploads\/2024\/08\/2024-11-17-Coach-Canada-bus-for-Downtown-Toronto-tour-232x300.jpg 232w, https:\/\/martinluther.ca\/wp-content\/uploads\/2024\/08\/2024-11-17-Coach-Canada-bus-for-Downtown-Toronto-tour-791x1024.jpg 791w, https:\/\/martinluther.ca\/wp-content\/uploads\/2024\/08\/2024-11-17-Coach-Canada-bus-for-Downtown-Toronto-tour-768x994.jpg 768w, https:\/\/martinluther.ca\/wp-content\/uploads\/2024\/08\/2024-11-17-Coach-Canada-bus-for-Downtown-Toronto-tour-1187x1536.jpg 1187w, https:\/\/martinluther.ca\/wp-content\/uploads\/2024\/08\/2024-11-17-Coach-Canada-bus-for-Downtown-Toronto-tour-1583x2048.jpg 1583w\" sizes=\"auto, (max-width: 1700px) 100vw, 1700px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-49610\" src=\"https:\/\/martinluther.ca\/wp-content\/uploads\/2024\/08\/2024-11-17-Bus-Tour-Downtown-Toronto-seats-inside.jpg\" alt=\"\" width=\"640\" height=\"480\" srcset=\"https:\/\/martinluther.ca\/wp-content\/uploads\/2024\/08\/2024-11-17-Bus-Tour-Downtown-Toronto-seats-inside.jpg 640w, https:\/\/martinluther.ca\/wp-content\/uploads\/2024\/08\/2024-11-17-Bus-Tour-Downtown-Toronto-seats-inside-300x225.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>UPDATE 6. Oktober 2024: Aufgrund mangelnder Anmeldungen abgesagt. Verschoben auf Fr\u00fchjahr 2025. Orginalbeitrag 0. August 2024: Egal ob Sie neu in Toronto sind, oder seit der COVID-Lockdownzeit (oder noch l\u00e4nger) nicht mehr in der Innenstadt waren, k\u00f6nnen Sie nun die Stadt im Komfort eines luxuri\u00f6sen, klimatisierten Reisebusses (mit 56 Sitzen) neu entdecken! Sie erleben eine&hellip;<\/p>\n","protected":false},"author":9,"featured_media":50063,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[69],"tags":[],"post_series":[],"class_list":["post-49642","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-blog-german","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Stadttour durch das Herzen Torontos \u2014im Luxusbus\u2014 am 17. 11. 2024 f\u00fcr deutschsprachigen Senioren - Martin Luther Evangelische Kirche Toronto<\/title>\n<meta name=\"description\" content=\"Bustour f\u00fcr deutschsprachige Senioren durch Downtown-Toronto am Sonntag, dem 17.11.2024\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/martinluther.ca\/de\/2024\/08\/downtown-toronto-mit-dem-bus-am-sonntag-17-november-2024-fur-deutschsprachige-senioren\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Stadttour durch das Herzen Torontos \u2014im Luxusbus\u2014 am 17. 11. 2024 f\u00fcr deutschsprachigen Senioren - Martin Luther Evangelische Kirche Toronto\" \/>\n<meta property=\"og:description\" content=\"Bustour f\u00fcr deutschsprachige Senioren durch Downtown-Toronto am Sonntag, dem 17.11.2024\" \/>\n<meta property=\"og:url\" content=\"https:\/\/martinluther.ca\/de\/2024\/08\/downtown-toronto-mit-dem-bus-am-sonntag-17-november-2024-fur-deutschsprachige-senioren\/\" \/>\n<meta property=\"og:site_name\" content=\"Martin Luther Evangelische Kirche Toronto\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/martinlutherchurchtoronto\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-09T14:34:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-15T00:33:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/martinluther.ca\/wp-content\/uploads\/2024\/10\/CANCELLED-Toronto-Bus-Tour-Nov17-2024-image-ad.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mona Kakoschke Frantzke\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mona Kakoschke Frantzke\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/martinluther.ca\\\/de\\\/2024\\\/08\\\/downtown-toronto-mit-dem-bus-am-sonntag-17-november-2024-fur-deutschsprachige-senioren\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/martinluther.ca\\\/de\\\/2024\\\/08\\\/downtown-toronto-mit-dem-bus-am-sonntag-17-november-2024-fur-deutschsprachige-senioren\\\/\"},\"author\":{\"name\":\"Mona Kakoschke Frantzke\",\"@id\":\"https:\\\/\\\/martinluther.ca\\\/de\\\/#\\\/schema\\\/person\\\/815c51710f70b050f0476f18da6b0c8f\"},\"headline\":\"Stadttour durch das Herzen Torontos \u2014im Luxusbus\u2014 am 17. 11. 2024 f\u00fcr deutschsprachigen Senioren\",\"datePublished\":\"2024-08-09T14:34:04+00:00\",\"dateModified\":\"2024-10-15T00:33:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/martinluther.ca\\\/de\\\/2024\\\/08\\\/downtown-toronto-mit-dem-bus-am-sonntag-17-november-2024-fur-deutschsprachige-senioren\\\/\"},\"wordCount\":454,\"publisher\":{\"@id\":\"https:\\\/\\\/martinluther.ca\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/martinluther.ca\\\/de\\\/2024\\\/08\\\/downtown-toronto-mit-dem-bus-am-sonntag-17-november-2024-fur-deutschsprachige-senioren\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/martinluther.ca\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/CANCELLED-Toronto-Bus-Tour-Nov17-2024-image-ad.jpg\",\"articleSection\":[\"News Blog - German\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/martinluther.ca\\\/de\\\/2024\\\/08\\\/downtown-toronto-mit-dem-bus-am-sonntag-17-november-2024-fur-deutschsprachige-senioren\\\/\",\"url\":\"https:\\\/\\\/martinluther.ca\\\/de\\\/2024\\\/08\\\/downtown-toronto-mit-dem-bus-am-sonntag-17-november-2024-fur-deutschsprachige-senioren\\\/\",\"name\":\"Stadttour durch das Herzen Torontos \u2014im Luxusbus\u2014 am 17. 11. 2024 f\u00fcr deutschsprachigen Senioren - Martin Luther Evangelische Kirche Toronto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/martinluther.ca\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/martinluther.ca\\\/de\\\/2024\\\/08\\\/downtown-toronto-mit-dem-bus-am-sonntag-17-november-2024-fur-deutschsprachige-senioren\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/martinluther.ca\\\/de\\\/2024\\\/08\\\/downtown-toronto-mit-dem-bus-am-sonntag-17-november-2024-fur-deutschsprachige-senioren\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/martinluther.ca\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/CANCELLED-Toronto-Bus-Tour-Nov17-2024-image-ad.jpg\",\"datePublished\":\"2024-08-09T14:34:04+00:00\",\"dateModified\":\"2024-10-15T00:33:12+00:00\",\"description\":\"Bustour f\u00fcr deutschsprachige Senioren durch Downtown-Toronto am Sonntag, dem 17.11.2024\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/martinluther.ca\\\/de\\\/2024\\\/08\\\/downtown-toronto-mit-dem-bus-am-sonntag-17-november-2024-fur-deutschsprachige-senioren\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/martinluther.ca\\\/de\\\/2024\\\/08\\\/downtown-toronto-mit-dem-bus-am-sonntag-17-november-2024-fur-deutschsprachige-senioren\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/martinluther.ca\\\/de\\\/2024\\\/08\\\/downtown-toronto-mit-dem-bus-am-sonntag-17-november-2024-fur-deutschsprachige-senioren\\\/#primaryimage\",\"url\":\"https:\\\/\\\/martinluther.ca\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/CANCELLED-Toronto-Bus-Tour-Nov17-2024-image-ad.jpg\",\"contentUrl\":\"https:\\\/\\\/martinluther.ca\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/CANCELLED-Toronto-Bus-Tour-Nov17-2024-image-ad.jpg\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/martinluther.ca\\\/de\\\/2024\\\/08\\\/downtown-toronto-mit-dem-bus-am-sonntag-17-november-2024-fur-deutschsprachige-senioren\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/martinluther.ca\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Stadttour durch das Herzen Torontos \u2014im Luxusbus\u2014 am 17. 11. 2024 f\u00fcr deutschsprachigen Senioren\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/martinluther.ca\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/martinluther.ca\\\/de\\\/\",\"name\":\"Martin Luther Evangelical Church Toronto\",\"description\":\"Deutsch &amp; Englisch\",\"publisher\":{\"@id\":\"https:\\\/\\\/martinluther.ca\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/martinluther.ca\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/martinluther.ca\\\/de\\\/#organization\",\"name\":\"Martin Luther Evangelical Church Toronto\",\"url\":\"https:\\\/\\\/martinluther.ca\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/martinluther.ca\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/martinluther.ca\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/ml-logo-300.png\",\"contentUrl\":\"https:\\\/\\\/martinluther.ca\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/ml-logo-300.png\",\"width\":300,\"height\":150,\"caption\":\"Martin Luther Evangelical Church Toronto\"},\"image\":{\"@id\":\"https:\\\/\\\/martinluther.ca\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/martinlutherchurchtoronto\",\"https:\\\/\\\/www.instagram.com\\\/lutheransbythelake\\\/\",\"https:\\\/\\\/www.youtube.com\\\/MartinLutherChurchToronto\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/martinluther.ca\\\/de\\\/#\\\/schema\\\/person\\\/815c51710f70b050f0476f18da6b0c8f\",\"name\":\"Mona Kakoschke Frantzke\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0deb16854ca545cd2e9fc8001ca110d262b80d5c8317b38dc542265fbea0ed19?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0deb16854ca545cd2e9fc8001ca110d262b80d5c8317b38dc542265fbea0ed19?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0deb16854ca545cd2e9fc8001ca110d262b80d5c8317b38dc542265fbea0ed19?s=96&d=mm&r=g\",\"caption\":\"Mona Kakoschke Frantzke\"},\"url\":false}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Stadttour durch das Herzen Torontos \u2014im Luxusbus\u2014 am 17. 11. 2024 f\u00fcr deutschsprachigen Senioren - Martin Luther Evangelische Kirche Toronto","description":"Bustour f\u00fcr deutschsprachige Senioren durch Downtown-Toronto am Sonntag, dem 17.11.2024","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/martinluther.ca\/de\/2024\/08\/downtown-toronto-mit-dem-bus-am-sonntag-17-november-2024-fur-deutschsprachige-senioren\/","og_locale":"de_DE","og_type":"article","og_title":"Stadttour durch das Herzen Torontos \u2014im Luxusbus\u2014 am 17. 11. 2024 f\u00fcr deutschsprachigen Senioren - Martin Luther Evangelische Kirche Toronto","og_description":"Bustour f\u00fcr deutschsprachige Senioren durch Downtown-Toronto am Sonntag, dem 17.11.2024","og_url":"https:\/\/martinluther.ca\/de\/2024\/08\/downtown-toronto-mit-dem-bus-am-sonntag-17-november-2024-fur-deutschsprachige-senioren\/","og_site_name":"Martin Luther Evangelische Kirche Toronto","article_publisher":"https:\/\/www.facebook.com\/martinlutherchurchtoronto","article_published_time":"2024-08-09T14:34:04+00:00","article_modified_time":"2024-10-15T00:33:12+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/martinluther.ca\/wp-content\/uploads\/2024\/10\/CANCELLED-Toronto-Bus-Tour-Nov17-2024-image-ad.jpg","type":"image\/jpeg"}],"author":"Mona Kakoschke Frantzke","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Mona Kakoschke Frantzke","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/martinluther.ca\/de\/2024\/08\/downtown-toronto-mit-dem-bus-am-sonntag-17-november-2024-fur-deutschsprachige-senioren\/#article","isPartOf":{"@id":"https:\/\/martinluther.ca\/de\/2024\/08\/downtown-toronto-mit-dem-bus-am-sonntag-17-november-2024-fur-deutschsprachige-senioren\/"},"author":{"name":"Mona Kakoschke Frantzke","@id":"https:\/\/martinluther.ca\/de\/#\/schema\/person\/815c51710f70b050f0476f18da6b0c8f"},"headline":"Stadttour durch das Herzen Torontos \u2014im Luxusbus\u2014 am 17. 11. 2024 f\u00fcr deutschsprachigen Senioren","datePublished":"2024-08-09T14:34:04+00:00","dateModified":"2024-10-15T00:33:12+00:00","mainEntityOfPage":{"@id":"https:\/\/martinluther.ca\/de\/2024\/08\/downtown-toronto-mit-dem-bus-am-sonntag-17-november-2024-fur-deutschsprachige-senioren\/"},"wordCount":454,"publisher":{"@id":"https:\/\/martinluther.ca\/de\/#organization"},"image":{"@id":"https:\/\/martinluther.ca\/de\/2024\/08\/downtown-toronto-mit-dem-bus-am-sonntag-17-november-2024-fur-deutschsprachige-senioren\/#primaryimage"},"thumbnailUrl":"https:\/\/martinluther.ca\/wp-content\/uploads\/2024\/10\/CANCELLED-Toronto-Bus-Tour-Nov17-2024-image-ad.jpg","articleSection":["News Blog - German"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/martinluther.ca\/de\/2024\/08\/downtown-toronto-mit-dem-bus-am-sonntag-17-november-2024-fur-deutschsprachige-senioren\/","url":"https:\/\/martinluther.ca\/de\/2024\/08\/downtown-toronto-mit-dem-bus-am-sonntag-17-november-2024-fur-deutschsprachige-senioren\/","name":"Stadttour durch das Herzen Torontos \u2014im Luxusbus\u2014 am 17. 11. 2024 f\u00fcr deutschsprachigen Senioren - Martin Luther Evangelische Kirche Toronto","isPartOf":{"@id":"https:\/\/martinluther.ca\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/martinluther.ca\/de\/2024\/08\/downtown-toronto-mit-dem-bus-am-sonntag-17-november-2024-fur-deutschsprachige-senioren\/#primaryimage"},"image":{"@id":"https:\/\/martinluther.ca\/de\/2024\/08\/downtown-toronto-mit-dem-bus-am-sonntag-17-november-2024-fur-deutschsprachige-senioren\/#primaryimage"},"thumbnailUrl":"https:\/\/martinluther.ca\/wp-content\/uploads\/2024\/10\/CANCELLED-Toronto-Bus-Tour-Nov17-2024-image-ad.jpg","datePublished":"2024-08-09T14:34:04+00:00","dateModified":"2024-10-15T00:33:12+00:00","description":"Bustour f\u00fcr deutschsprachige Senioren durch Downtown-Toronto am Sonntag, dem 17.11.2024","breadcrumb":{"@id":"https:\/\/martinluther.ca\/de\/2024\/08\/downtown-toronto-mit-dem-bus-am-sonntag-17-november-2024-fur-deutschsprachige-senioren\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/martinluther.ca\/de\/2024\/08\/downtown-toronto-mit-dem-bus-am-sonntag-17-november-2024-fur-deutschsprachige-senioren\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/martinluther.ca\/de\/2024\/08\/downtown-toronto-mit-dem-bus-am-sonntag-17-november-2024-fur-deutschsprachige-senioren\/#primaryimage","url":"https:\/\/martinluther.ca\/wp-content\/uploads\/2024\/10\/CANCELLED-Toronto-Bus-Tour-Nov17-2024-image-ad.jpg","contentUrl":"https:\/\/martinluther.ca\/wp-content\/uploads\/2024\/10\/CANCELLED-Toronto-Bus-Tour-Nov17-2024-image-ad.jpg","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/martinluther.ca\/de\/2024\/08\/downtown-toronto-mit-dem-bus-am-sonntag-17-november-2024-fur-deutschsprachige-senioren\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/martinluther.ca\/de\/"},{"@type":"ListItem","position":2,"name":"Stadttour durch das Herzen Torontos \u2014im Luxusbus\u2014 am 17. 11. 2024 f\u00fcr deutschsprachigen Senioren"}]},{"@type":"WebSite","@id":"https:\/\/martinluther.ca\/de\/#website","url":"https:\/\/martinluther.ca\/de\/","name":"Martin Luther Evangelical Church Toronto","description":"Deutsch &amp; Englisch","publisher":{"@id":"https:\/\/martinluther.ca\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/martinluther.ca\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/martinluther.ca\/de\/#organization","name":"Martin Luther Evangelical Church Toronto","url":"https:\/\/martinluther.ca\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/martinluther.ca\/de\/#\/schema\/logo\/image\/","url":"https:\/\/martinluther.ca\/wp-content\/uploads\/2016\/12\/ml-logo-300.png","contentUrl":"https:\/\/martinluther.ca\/wp-content\/uploads\/2016\/12\/ml-logo-300.png","width":300,"height":150,"caption":"Martin Luther Evangelical Church Toronto"},"image":{"@id":"https:\/\/martinluther.ca\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/martinlutherchurchtoronto","https:\/\/www.instagram.com\/lutheransbythelake\/","https:\/\/www.youtube.com\/MartinLutherChurchToronto"]},{"@type":"Person","@id":"https:\/\/martinluther.ca\/de\/#\/schema\/person\/815c51710f70b050f0476f18da6b0c8f","name":"Mona Kakoschke Frantzke","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/0deb16854ca545cd2e9fc8001ca110d262b80d5c8317b38dc542265fbea0ed19?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0deb16854ca545cd2e9fc8001ca110d262b80d5c8317b38dc542265fbea0ed19?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0deb16854ca545cd2e9fc8001ca110d262b80d5c8317b38dc542265fbea0ed19?s=96&d=mm&r=g","caption":"Mona Kakoschke Frantzke"},"url":false}]}},"_links":{"self":[{"href":"https:\/\/martinluther.ca\/de\/wp-json\/wp\/v2\/posts\/49642","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/martinluther.ca\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/martinluther.ca\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/martinluther.ca\/de\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/martinluther.ca\/de\/wp-json\/wp\/v2\/comments?post=49642"}],"version-history":[{"count":19,"href":"https:\/\/martinluther.ca\/de\/wp-json\/wp\/v2\/posts\/49642\/revisions"}],"predecessor-version":[{"id":50065,"href":"https:\/\/martinluther.ca\/de\/wp-json\/wp\/v2\/posts\/49642\/revisions\/50065"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/martinluther.ca\/de\/wp-json\/wp\/v2\/media\/50063"}],"wp:attachment":[{"href":"https:\/\/martinluther.ca\/de\/wp-json\/wp\/v2\/media?parent=49642"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/martinluther.ca\/de\/wp-json\/wp\/v2\/categories?post=49642"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/martinluther.ca\/de\/wp-json\/wp\/v2\/tags?post=49642"},{"taxonomy":"post_series","embeddable":true,"href":"https:\/\/martinluther.ca\/de\/wp-json\/wp\/v2\/post_series?post=49642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}